{"id":595,"count":8,"description":"","link":"https:\/\/freieszenemuc.de\/tag\/theater-viel-laerm-um-nichts\/","name":"Theater Viel L\u00e4rm um Nichts","slug":"theater-viel-laerm-um-nichts","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/freieszenemuc.de\/en\/wp-json\/wp\/v2\/tags\/595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/freieszenemuc.de\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/freieszenemuc.de\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/freieszenemuc.de\/en\/wp-json\/wp\/v2\/posts?tags=595"},{"href":"https:\/\/freieszenemuc.de\/en\/wp-json\/wp\/v2\/tribe_events?tags=595"},{"href":"https:\/\/freieszenemuc.de\/en\/wp-json\/wp\/v2\/tec_calendar_embed?tags=595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}