{"id":10026861,"date":"2022-08-01T20:02:07","date_gmt":"2022-08-01T18:02:07","guid":{"rendered":"https:\/\/frei.devwebspace.info\/?post_type=tribe_events&amp;p=25750"},"modified":"2022-08-01T20:02:07","modified_gmt":"2022-08-01T18:02:07","slug":"may-zarhy-libelle-4","status":"publish","type":"tribe_events","link":"https:\/\/freieszenemuc.de\/en\/event\/may-zarhy-libelle-4\/2023-01-21\/","title":{"rendered":"May Zarhy: Libelle"},"content":{"rendered":"<p>Jeden Tag, wenn der richtige Moment gekommen ist, schlie\u00dft Libelle ihre Augen, erfindet ihre eigene Sprache und erz\u00e4hlt uns ihre Fantasiegeschichte. Es ist eine Geschichte, die uns einl\u00e4dt, sie zu sp\u00fcren anstatt sie zu lesen oder verstehen zu m\u00fcssen.<\/p>\n<p>In dem Tanzst\u00fcck, das gleichzeitig ein Konzert ist, spielt Libelle mit ihren Freund*innen. Sie vermischen ihre Stimmen mit Trommelmusik und formen daraus Lieder oder Bewegungen. Zu elektronischen und akustischen Kl\u00e4ngen verwandeln sie sich zusammen in bunte, mysteri\u00f6se Wesen.<\/p>\n<p><strong>29.6. | 10 Uhr und 15 Uhr<br \/>\n30.6. | 10 Uhr<br \/>\n6 \u20ac erm. \/ 10 \u20ac<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jeden Tag, wenn der richtige Moment gekommen ist, schlie\u00dft Libelle ihre Augen, erfindet ihre eigene Sprache und erz\u00e4hlt uns ihre Fantasiegeschichte. Es ist eine Geschichte, die uns einl\u00e4dt, sie zu [&hellip;]<\/p>\n","protected":false},"author":232,"featured_media":25751,"template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[],"tribe_events_cat":[32],"class_list":["post-10026861","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-tanz","cat_tanz","tribe-recurring-event","tribe-recurring-event-parent"],"acf":[],"ticketed":false,"_links":{"self":[{"href":"https:\/\/freieszenemuc.de\/en\/wp-json\/wp\/v2\/tribe_events\/10026861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/freieszenemuc.de\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/freieszenemuc.de\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/freieszenemuc.de\/en\/wp-json\/wp\/v2\/users\/232"}],"version-history":[{"count":0,"href":"https:\/\/freieszenemuc.de\/en\/wp-json\/wp\/v2\/tribe_events\/10026861\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/freieszenemuc.de\/en\/wp-json\/wp\/v2\/media\/25751"}],"wp:attachment":[{"href":"https:\/\/freieszenemuc.de\/en\/wp-json\/wp\/v2\/media?parent=10026861"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/freieszenemuc.de\/en\/wp-json\/wp\/v2\/tags?post=10026861"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/freieszenemuc.de\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=10026861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}