{"id":10036717,"date":"2026-05-07T11:37:37","date_gmt":"2026-05-07T09:37:37","guid":{"rendered":"https:\/\/freieszenemuc.de\/?post_type=tribe_events&#038;p=50315"},"modified":"2026-05-07T11:39:35","modified_gmt":"2026-05-07T09:39:35","slug":"athanor-akademie-fuer-darstellende-kunst-abschlussmonologe","status":"publish","type":"tribe_events","link":"https:\/\/freieszenemuc.de\/en\/event\/athanor-akademie-fuer-darstellende-kunst-abschlussmonologe\/2026-06-06\/","title":{"rendered":"Athanor Akademie f\u00fcr Darstellende Kunst: Abschlussmonologe"},"content":{"rendered":"<p>die Absolventinnen und Absolventen 2026\u2028 der Athanor Akademie f\u00fcr Darstellende Kunst, Passau<br \/>\nzu Gast bei uns im Theater!<\/p>\n<p>Termine:<br \/>\n5. &amp; 6. Juni 2026 | 20 Uhr<\/p>\n<p>Nach dem gro\u00dfen Erfolg im letzten Jahr freuen wir uns sehr, auch heuer die Athanor Akademie f\u00fcr Darstellende Kunst Passau wieder mit einem besonderen Abend bei uns zu Gast zu haben. Die diesj\u00e4hrigen Schauspielabsolventinnen und Absolventen pr\u00e4sentieren eine Auswahl ihre Abschlussmonologe \u2013 eine facettenreiche Auswahl aus klassischen bis zeitgen\u00f6ssischen Werken. F\u00fcr Fachpublikum, Theaterverantwortliche und nat\u00fcrlich alle sonstigen Theaterbegeisterte!<br \/>\nEintritt frei, Spenden erw\u00fcnscht.<\/p>\n<p>mit<br \/>\nHannes Kainz, Hanno Dasenbrock, \u00a0Jasmin Jantima Wojke, \u00a0Josef Andreas Wallner, \u00a0Julia Haas, \u00a0Julia Jaskiola, \u00a0Konstantia Meinzer, \u00a0Lena-Maria K\u00f6hler, \u00a0Maja Selina Luisa Reif, \u00a0Marvin Steglich, \u00a0Mio Wojtaszek, \u00a0Philipp Jouaux<\/p>\n<p>Gestaltung des Abends: Mirkus Hahn<br \/>\nBegleitung der Monologe: Arno Kleinofen, Sarah Schuchardt, Florian von Hoermann, Andrea Frohn, Helmut Schwaiger\u00a0Technische Einrichtung: Max Reitmayer<\/p>\n<p>Achtung!<br \/>\nAus verlagsrechtlichen Gr\u00fcnden ist diese Veranstaltung nicht im freien Verkauf.<br \/>\nDer Eintritt ist frei, aber nur mit Anmeldung \/ Einladung m\u00f6glich. Eine Einladung bekommt ihr per Mail zugeschickt, wenn ihr euch \u00fcber das Formular (Button) anmeldet. Es ist ganz einfach.<br \/>\nIhr k\u00f6nnt aber auch gerne abends spontan kommen. Einlass ist 10 Minuten vor Beginn.<\/p>\n<p>Die jungen Talente der Athanor Akademie und wir freuen uns auf euch!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>die Absolventinnen und Absolventen 2026\u2028 der Athanor Akademie f\u00fcr Darstellende Kunst, Passau<br \/>\nzu Gast bei uns im Theater!<\/p>\n","protected":false},"author":160,"featured_media":50316,"template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[506,595],"tribe_events_cat":[30],"class_list":["post-10036717","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tag-schauspiel","tag-theater-viel-laerm-um-nichts","tribe_events_cat-theater","cat_theater","tribe-recurring-event","tribe-recurring-event-parent"],"acf":[],"ticketed":false,"_links":{"self":[{"href":"https:\/\/freieszenemuc.de\/en\/wp-json\/wp\/v2\/tribe_events\/10036717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/freieszenemuc.de\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/freieszenemuc.de\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/freieszenemuc.de\/en\/wp-json\/wp\/v2\/users\/160"}],"version-history":[{"count":0,"href":"https:\/\/freieszenemuc.de\/en\/wp-json\/wp\/v2\/tribe_events\/10036717\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/freieszenemuc.de\/en\/wp-json\/wp\/v2\/media\/50316"}],"wp:attachment":[{"href":"https:\/\/freieszenemuc.de\/en\/wp-json\/wp\/v2\/media?parent=10036717"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/freieszenemuc.de\/en\/wp-json\/wp\/v2\/tags?post=10036717"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/freieszenemuc.de\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=10036717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}